{"id":1879,"date":"2017-08-15T17:40:04","date_gmt":"2017-08-15T14:40:04","guid":{"rendered":"http:\/\/eksensaglik.com\/?p=1879"},"modified":"2023-06-24T06:38:38","modified_gmt":"2023-06-24T06:38:38","slug":"ms-multipl-skleroz-nedir","status":"publish","type":"post","link":"https:\/\/eksensaglik.com\/fr\/ms-multipl-skleroz-nedir\/","title":{"rendered":"Qu&#039;est-ce que la SEP scl\u00e9rose en plaques ?"},"content":{"rendered":"<h2><strong>Qu&#039;est-ce que la SEP scl\u00e9rose en plaques ?<\/strong><\/h2>\n<p class=\"translation-block\"><strong>MS Multipl Skleroz <\/strong>, gen\u00e7 eri\u015fkinlerde g\u00f6r\u00fclen, genellikle alevlenmeler ve d\u00fczelmelerle seyreden ba\u011f\u0131\u015f\u0131kl\u0131k sistemine etkileyerek beyin ve umur i\u015fte bazen geri d\u00f6n\u00fclmez sorunlara yol a\u00e7an kronik bir hastal\u0131kt\u0131r. Genellikle 20-40 ya\u015flar\u0131 aras\u0131nda ba\u015flar\u2026<\/p>\n<h2><strong>Quels sont les sympt\u00f4mes cliniques de la scl\u00e9rose en plaques SEP?<\/strong><\/h2>\n<p class=\"translation-block\">G\u00f6rme kayb\u0131, duyu kayb\u0131, \u00e7ift g\u00f6rme, denge bozuklu\u011fu, depresyon, yorgunluk, kol ve bacaklarda uyu\u015fmalar, konu\u015fma bozukluklar\u0131, <strong>ba\u015f d\u00f6nmesi<\/strong>, kol ve bacaklarda g\u00fc\u00e7 kayb\u0131, idrar yapmada sorunlar ve cinsel sorunlar klinik belirtilerdir.<\/p>\n<p class=\"translation-block\"><strong>MS (Multipl Skleroz)<\/strong> hastal\u0131\u011f\u0131n\u0131n tedavisinde medikal tedavi ile birlikte <strong>fizik tedavi ve rehabilitasyon<\/strong> \u00e7ok \u00f6nemli bir yere sahiptir.<\/p>\n<h2><strong>Physioth\u00e9rapie et r\u00e9adaptation dans la SEP<\/strong><\/h2>\n<p class=\"translation-block\"><strong>MS (Multipl Skleroz)<\/strong> \u2018da kas zay\u0131fl\u0131klar\u0131, g\u00f6rme kay\u0131plar\u0131, de\u011fi\u015fmi\u015f duyu ve a\u011fr\u0131 alg\u0131s\u0131, yorgunluk, duygusal ve bili\u015fsel de\u011fi\u015fiklikler \u00e7ok s\u0131k g\u00f6r\u00fcl\u00fcr.<\/p>\n<p class=\"translation-block\">Bu belirtiler denge ve y\u00fcr\u00fcme sorunlar\u0131na ve ya\u015fam kalitesinde de\u011fi\u015fikliklere yol a\u00e7ar. \u00d6zellikle y\u00fcr\u00fcme sorunlar\u0131 ve <strong>denge kay\u0131plar\u0131<\/strong> g\u00fcnl\u00fck ya\u015fam aktivitelerini k\u0131s\u0131tlay\u0131c\u0131d\u0131r.<\/p>\n<p class=\"translation-block\">G\u00fcnl\u00fck ya\u015fam aktivitelerinin k\u0131s\u0131tlamas\u0131 ve bununla birlikte g\u00fcnl\u00fck harcanan enerji d\u00fczeyinin azalmas\u0131 <strong>MS (Multipl Skleroz)<\/strong> hastalar\u0131nda ayr\u0131ca obezite, osteoporoz, <strong>kardiyovask\u00fcler<\/strong> hastal\u0131klara neden olmaktad\u0131r.<\/p>\n<p class=\"translation-block\"><strong>D\u00fczenli egzersiz ve fiziksel aktivite<\/strong> ya\u015fam\u0131n t\u00fcm safhalar\u0131nda hastal\u0131klar\u0131 \u00f6nleme, kendini iyi hissetme ve ki\u015finin ya\u015fam kalitesini desteklemede \u00f6nemlidir.<\/p>\n<p class=\"translation-block\"><a href=\"http:\/\/eksensaglik.com\/fr\/multiple-skleroz-hasta-bakimi\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>MS (Multipl Skleroz)<\/strong><\/a> hastalar\u0131nda&nbsp; spinal kord yaralanmalar\u0131, travmatik <strong>beyin yaralanmalar\u0131 ve strok<\/strong> gibi di\u011fer hastal\u0131klara benzemeyen \u015fekilde sabit bir hastal\u0131k belirtisi yoktur.<\/p>\n<p>Les sympt\u00f4mes au cours de l&#039;\u00e9volution de la maladie peuvent varier, en particulier pendant les \u00e9pisodes. Par cons\u00e9quent, chaque patient doit \u00eatre \u00e9valu\u00e9 s\u00e9par\u00e9ment et inclus dans le programme d\u2019exercices.<\/p>\n<p class=\"translation-block\"><strong>MS (Multipl Skleroz)\u2019<\/strong>da egzersiz uygulamalar\u0131 \u00e7ok \u00f6nemlidir. Egzersizleri uygulamada herhangi bir protokol ya da s\u0131n\u0131r yoktur.<\/p>\n<p>Les patients atteints de scl\u00e9rose en plaques, pour b\u00e9n\u00e9ficier de l&#039;exercice dont ils ont besoin doivent \u00eatre priv\u00e9s et peuvent faire sans difficult\u00e9.<\/p>\n<p class=\"translation-block\"><strong>MS (Multipl Skleroz)<\/strong> hastalar\u0131n\u0131n yapt\u0131\u011f\u0131 egzersizler <strong>fizyoterapist<\/strong>ler taraf\u0131ndan belirlenmeli ve takip edilmelidir.<\/p>\n<p><strong>Quel est le r\u00f4le du physioth\u00e9rapeute dans la scl\u00e9rose en plaques?<\/strong><\/p>\n<p class=\"translation-block\"><strong>Fizyoterapist<\/strong>in rol\u00fc hastal\u0131k seyri boyunca de\u011fi\u015fir. <strong>MS Multipl Skleroz<\/strong>&nbsp;hastas\u0131n\u0131n hastaneye yat\u0131\u015f d\u00f6nemi, hastaneden \u00e7\u0131k\u0131\u015f ve sonraki d\u00f6nemlerde egzersiz konusunda dan\u0131\u015fabilece\u011fi bir <strong>fizyoterapist<\/strong>i olmal\u0131d\u0131r.<\/p>\n<p>Le physioth\u00e9rapeute doit aider le patient avec des exercices et des aides \u00e0 la marche pour am\u00e9liorer sa fonction apr\u00e8s une crise aigu\u00eb.<\/p>\n<p>Le positionnement des patients hospitalis\u00e9s, la respiration, le contr\u00f4le du tronc et les transferts devraient aider \u00e0 augmenter la force des membres sup\u00e9rieurs chez les patients qui ont perdu leur capacit\u00e9 de marcher dans des situations avanc\u00e9es.<\/p>\n<p class=\"translation-block\">Egzersiz uygulamalar\u0131na ba\u015flamadan \u00f6nce <strong>MS Multipl Skleroz<\/strong>&nbsp;hastalar\u0131 <strong>fizyoterapi<\/strong> a\u00e7\u0131s\u0131ndan de\u011ferlendirilmelidir.<\/p>\n<p>Le contr\u00f4le musculaire, le tonus musculaire, l&#039;amplitude des mouvements, l&#039;\u00e9quilibre de la position assise, du pied et de la marche doivent \u00eatre \u00e9valu\u00e9s. Des \u00e9valuations sensorielles doivent \u00eatre effectu\u00e9es et la s\u00e9lection des chaussures doit \u00eatre prise en compte.<\/p>\n<h2><strong>Quelles sont nos approches dans le processus de th\u00e9rapie physique?<\/strong><\/h2>\n<ul>\n<li>Nous am\u00e9liorons la conscience corporelle de nos patients<\/li>\n<li>Nous r\u00e9duisons l&#039;intention intentionnelle anormale de notre patient<\/li>\n<li>Nous commen\u00e7ons nos exercices avec le positionnement et les \u00e9tirements<\/li>\n<li>Nous fournissons une r\u00e9troaction \u00e0 notre patient avec diverses entr\u00e9es sensorielles afin de r\u00e9duire les pertes sensorielles<\/li>\n<li>Nous essayons d&#039;acqu\u00e9rir des comp\u00e9tences fonctionnelles en ayant beaucoup de pratique dans les activit\u00e9s de la vie quotidienne<\/li>\n<li>Nous appliquons progressivement l&#039;intensit\u00e9 de nos exercices, du plus simple au plus difficile, et prenons \u00e9galement en compte le rythme cardiaque et la fatigue de notre patient.<\/li>\n<li>Afin de bien marcher, nous accordons beaucoup d\u2019espace \u00e0 nos exercices de pr\u00e9paration \u00e0 la marche et d\u2019\u00e9quilibre.<\/li>\n<\/ul>\n<p>Rappelez-vous<\/p>\n<p class=\"translation-block\"><strong>MS Multipl Skleroz<\/strong>, ASLA \u00c7ARES\u0130Z B\u0130R HASTALIK DE\u011e\u0130LD\u0130R.<\/p>\n<p>Il peut \u00eatre contr\u00f4l\u00e9 avec un traitement appropri\u00e9 et r\u00e9gulier et un mode de vie.<\/p>\n<p class=\"translation-block\">Yine unutmay\u0131n ki,&nbsp;<strong>MS Multipl Skleroz<\/strong>&nbsp;ya\u015fam\u0131 de\u011fil ya\u015fam kalitesini tehdit eden, ak\u0131lc\u0131 ve hasta, aile, hekim ve fizyoterapist i\u015f birli\u011fi ile s\u0131k\u0131 y\u00f6netilmesi gereken n\u00f6rolojik bir hastal\u0131kt\u0131r.<\/p>\n<h3>Traitement de la SEP dans notre centre<\/h3>\n<p><a href=\"https:\/\/eksensaglik.com\/fr\/yatarak-fizik-tedavi-ve-rehabilitasyon-hizmeti\/\">physioth\u00e9rapie en milieu hospitalier<\/a> merkezimizde bulunan uzman ekiplerimizle 7\/24 sa\u011fl\u0131k hizmeti vermekteyiz. Gerek fel\u00e7 <a href=\"https:\/\/eksensaglik.com\/fr\/hizmetlerimiz\/felc-inme-hemipleji-tedavisi\/\">coup<\/a> tedavisi gerekse ms tedavisi uzman doktorlar\u0131m\u0131z taraf\u0131ndan ger\u00e7ekle\u015ftirilmektedir. Hem\u015fireler s\u00fcrekli hastalar\u0131m\u0131z\u0131n Kontrollerini sa\u011flamakta ve herhangi bir olumsuz durum kar\u015f\u0131s\u0131nda doktorun g\u00f6zetimi alt\u0131nda m\u00fcdahele sa\u011flanmaktad\u0131r.<\/p>\n<p>Hastalar\u0131m\u0131z\u0131n t\u0131bbi bak\u0131m ve tedavilerinin yan\u0131nda <a href=\"https:\/\/eksensaglik.com\/fr\/yatili-fizik-tedavide-psikolojik-destek-ve-onemi\/\">psikolojik<\/a> rehabilitasyonlar\u0131n\u0131n da \u00e7ok \u00f6nemli oldu\u011funa inan\u0131yoruz. Bu nedenle <a href=\"https:\/\/eksensaglik.com\/fr\/yatili-fizik-tedavide-psikolojik-destek-ve-onemi\/\">psikolojik<\/a> destek s\u00fcrekli olarak sa\u011flanmakta ve hastalar\u0131m\u0131z\u0131n moral motivasyonunu en \u00fcst d\u00fczeyde tutulmaya Gayret g\u00f6sterilmektedir.<\/p>\n<p>Dans le m\u00eame temps, la socialisation de nos patients est assur\u00e9e en organisant de temps en temps des programmes de socialisation de nos patients, et il est assur\u00e9 que le patient garde le moral en sortant de sa coquille et en se m\u00ealant \u00e0 la soci\u00e9t\u00e9 ou \u00e0 d&#039;autres patients .<\/p>\n<p>Pour plus d&#039;informations, vous pouvez nous appeler ou nous envoyer un message sur le site.<\/p>\n<p>Nous vous souhaitons une bonne journ\u00e9e!<\/p>\n<p class=\"translation-block\"><a href=\"https:\/\/youtube.com\/eksensaglik\" target=\"_blank\" rel=\"noopener\">Youtube<\/a> videolar\u0131m\u0131za g\u00f6z atabilirsiniz..<\/p>","protected":false},"excerpt":{"rendered":"<p>MS Multipl Skleroz Nedir? MS Multipl Skleroz , gen\u00e7 eri\u015fkinlerde g\u00f6r\u00fclen, genellikle alevlenmeler ve d\u00fczelmelerle seyreden ba\u011f\u0131\u015f\u0131kl\u0131k sistemine etkileyerek beyin ve umur i\u015fte bazen geri d\u00f6n\u00fclmez sorunlara yol a\u00e7an kronik bir hastal\u0131kt\u0131r. Genellikle 20-40 ya\u015flar\u0131 aras\u0131nda ba\u015flar\u2026 MS Multipl Skleroz\u2019de G\u00f6r\u00fclen Klinik Belirtiler Nelerdir? G\u00f6rme kayb\u0131, duyu kayb\u0131, \u00e7ift g\u00f6rme, denge bozuklu\u011fu, depresyon, yorgunluk, kol &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/eksensaglik.com\/fr\/ms-multipl-skleroz-nedir\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;MS Multipl Skleroz Nedir?&nbsp;&raquo;<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":295,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[397,65],"tags":[137,235,236,237],"class_list":["post-1879","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-norolojik-rehabilitasyon","category-yazilar","tag-emes-hastaligi","tag-emes-tedavisi","tag-ms-multipl-skleroz-nedir","tag-ms-tedavisi"],"jetpack_featured_media_url":"https:\/\/eksensaglik.com\/wp-content\/uploads\/2016\/12\/fizik-tedavi-ve-rehabilitasyon-eksen-saglik-multipl-skleroz-tedavisi-tedavisi-rehabilitasyonu.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eksensaglik.com\/fr\/wp-json\/wp\/v2\/posts\/1879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eksensaglik.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eksensaglik.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eksensaglik.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eksensaglik.com\/fr\/wp-json\/wp\/v2\/comments?post=1879"}],"version-history":[{"count":1,"href":"https:\/\/eksensaglik.com\/fr\/wp-json\/wp\/v2\/posts\/1879\/revisions"}],"predecessor-version":[{"id":9630,"href":"https:\/\/eksensaglik.com\/fr\/wp-json\/wp\/v2\/posts\/1879\/revisions\/9630"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eksensaglik.com\/fr\/wp-json\/wp\/v2\/media\/295"}],"wp:attachment":[{"href":"https:\/\/eksensaglik.com\/fr\/wp-json\/wp\/v2\/media?parent=1879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eksensaglik.com\/fr\/wp-json\/wp\/v2\/categories?post=1879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eksensaglik.com\/fr\/wp-json\/wp\/v2\/tags?post=1879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}