{"id":397,"count":74,"description":"","link":"https:\/\/eksensaglik.com\/de\/kategori\/yazilar\/norolojik-rehabilitasyon\/","name":"Neurologische Rehabilitation","slug":"norolojik-rehabilitasyon","taxonomy":"category","parent":65,"meta":[],"_links":{"self":[{"href":"https:\/\/eksensaglik.com\/de\/wp-json\/wp\/v2\/categories\/397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eksensaglik.com\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/eksensaglik.com\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/eksensaglik.com\/de\/wp-json\/wp\/v2\/categories\/65"}],"wp:post_type":[{"href":"https:\/\/eksensaglik.com\/de\/wp-json\/wp\/v2\/posts?categories=397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}